{"id":360,"date":"2016-01-06T18:55:35","date_gmt":"2016-01-06T21:55:35","guid":{"rendered":"http:\/\/www.falaroca.com\/mapa\/?p=360"},"modified":"2016-01-26T21:20:49","modified_gmt":"2016-01-27T00:20:49","slug":"atelie-do-tio-lino","status":"publish","type":"post","link":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/","title":{"rendered":"Ateli\u00ea do Tio Lino"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"borda-imagens alignright wp-image-890\" src=\"http:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg\" alt=\"1890999_868083219873602_4199188144354398371_n\" width=\"351\" height=\"263\" srcset=\"https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg 500w, https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n-270x203.jpg 270w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/>O Ateli\u00ea do Tio Lino \u00e9 um est\u00fadio de arte criado\u00a0pelo ex-presidente da associa\u00e7\u00e3o de moradores da Rocinha, Lino dos Santos Filho. Ele faleceu em 2014, aos 58 anos.<!--more--><\/p>\n<p style=\"text-align: justify;\">Em sua ONG, Lino oferecia aulas de refor\u00e7o escolar, cursos e oficinas de pintura, desenho e leitura. Muitos de seus alunos se tornaram agentes multiplicadores dentro da Rocinha.<\/p>\n<p style=\"text-align: justify;\">Nos \u00faltimos anos\u00a0teve seu ateli\u00ea reformado, com ajuda de volunt\u00e1rios brasileiros e internacionais. Diagnosticado com diabetes, n\u00e3o desistiu de lutar pelas crian\u00e7as em sua sede na localidade Val\u00e3o. Tio Lino deixou um legado de luta, solidariedade e mesmo com muitas dificuldades, manteve seu sorriso e amor pela Rocinha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Ateli\u00ea do Tio Lino \u00e9 um est\u00fadio de arte criado\u00a0pelo ex-presidente da associa\u00e7\u00e3o de moradores da Rocinha, Lino dos Santos Filho. Ele faleceu em 2014, aos 58 anos.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-360","post","type-post","status-publish","format-standard","hentry","category-centro-social"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha\" \/>\n<meta property=\"og:description\" content=\"O Ateli\u00ea do Tio Lino \u00e9 um est\u00fadio de arte criado\u00a0pelo ex-presidente da associa\u00e7\u00e3o de moradores da Rocinha, Lino dos Santos Filho. Ele faleceu em 2014, aos 58 anos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/\" \/>\n<meta property=\"og:site_name\" content=\"Mapa Cultural da Rocinha\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-06T21:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-27T00:20:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg\" \/>\n<meta name=\"author\" content=\"Michel Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/\",\"url\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/\",\"name\":\"Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha\",\"isPartOf\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg\",\"datePublished\":\"2016-01-06T21:55:35+00:00\",\"dateModified\":\"2016-01-27T00:20:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage\",\"url\":\"https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg\",\"contentUrl\":\"https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.falaroca.com\/mapa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ateli\u00ea do Tio Lino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#website\",\"url\":\"https:\/\/www.falaroca.com\/mapa\/\",\"name\":\"Mapa Cultural da Rocinha\",\"description\":\"Mapa Cultural da Rocinha\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.falaroca.com\/mapa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb\",\"name\":\"Michel Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g\",\"caption\":\"Michel Silva\"},\"url\":\"https:\/\/www.falaroca.com\/mapa\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/","og_locale":"pt_BR","og_type":"article","og_title":"Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha","og_description":"O Ateli\u00ea do Tio Lino \u00e9 um est\u00fadio de arte criado\u00a0pelo ex-presidente da associa\u00e7\u00e3o de moradores da Rocinha, Lino dos Santos Filho. Ele faleceu em 2014, aos 58 anos.","og_url":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/","og_site_name":"Mapa Cultural da Rocinha","article_published_time":"2016-01-06T21:55:35+00:00","article_modified_time":"2016-01-27T00:20:49+00:00","og_image":[{"url":"http:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg","type":"","width":"","height":""}],"author":"Michel Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Michel Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/","url":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/","name":"Ateli\u00ea do Tio Lino - Mapa Cultural da Rocinha","isPartOf":{"@id":"https:\/\/www.falaroca.com\/mapa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage"},"image":{"@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage"},"thumbnailUrl":"http:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg","datePublished":"2016-01-06T21:55:35+00:00","dateModified":"2016-01-27T00:20:49+00:00","author":{"@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb"},"breadcrumb":{"@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#primaryimage","url":"https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg","contentUrl":"https:\/\/www.falaroca.com\/mapa\/wp-content\/uploads\/2016\/01\/1890999_868083219873602_4199188144354398371_n.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.falaroca.com\/mapa\/atelie-do-tio-lino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.falaroca.com\/mapa\/"},{"@type":"ListItem","position":2,"name":"Ateli\u00ea do Tio Lino"}]},{"@type":"WebSite","@id":"https:\/\/www.falaroca.com\/mapa\/#website","url":"https:\/\/www.falaroca.com\/mapa\/","name":"Mapa Cultural da Rocinha","description":"Mapa Cultural da Rocinha","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.falaroca.com\/mapa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb","name":"Michel Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g","caption":"Michel Silva"},"url":"https:\/\/www.falaroca.com\/mapa\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":5,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"predecessor-version":[{"id":893,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/360\/revisions\/893"}],"wp:attachment":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}