{"id":452,"date":"2016-01-14T14:46:35","date_gmt":"2016-01-14T17:46:35","guid":{"rendered":"http:\/\/www.falaroca.com\/mapa\/?p=452"},"modified":"2016-01-19T10:42:59","modified_gmt":"2016-01-19T13:42:59","slug":"praca-dos-predios-do-pac","status":"publish","type":"post","link":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/","title":{"rendered":"Pra\u00e7a da Conjunto Habitacional do PAC"},"content":{"rendered":"<p style=\"text-align: justify;\">A pra\u00e7a do Conjunto Habitacional do PAC foi constru\u00edda junto com os pr\u00e9dios durante as obras do PAC 1 pelo Governo Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pra\u00e7a do Conjunto Habitacional do PAC foi constru\u00edda junto com os pr\u00e9dios durante as obras do PAC 1 pelo Governo Federal.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-452","post","type-post","status-publish","format-standard","hentry","category-lazer"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha\" \/>\n<meta property=\"og:description\" content=\"A pra\u00e7a do Conjunto Habitacional do PAC foi constru\u00edda junto com os pr\u00e9dios durante as obras do PAC 1 pelo Governo Federal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/\" \/>\n<meta property=\"og:site_name\" content=\"Mapa Cultural da Rocinha\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-14T17:46:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-19T13:42:59+00:00\" \/>\n<meta name=\"author\" content=\"Michel Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel Silva\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/\",\"url\":\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/\",\"name\":\"Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha\",\"isPartOf\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#website\"},\"datePublished\":\"2016-01-14T17:46:35+00:00\",\"dateModified\":\"2016-01-19T13:42:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.falaroca.com\/mapa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pra\u00e7a da Conjunto Habitacional do PAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#website\",\"url\":\"https:\/\/www.falaroca.com\/mapa\/\",\"name\":\"Mapa Cultural da Rocinha\",\"description\":\"Mapa Cultural da Rocinha\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.falaroca.com\/mapa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb\",\"name\":\"Michel Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g\",\"caption\":\"Michel Silva\"},\"url\":\"https:\/\/www.falaroca.com\/mapa\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/","og_locale":"pt_BR","og_type":"article","og_title":"Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha","og_description":"A pra\u00e7a do Conjunto Habitacional do PAC foi constru\u00edda junto com os pr\u00e9dios durante as obras do PAC 1 pelo Governo Federal.","og_url":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/","og_site_name":"Mapa Cultural da Rocinha","article_published_time":"2016-01-14T17:46:35+00:00","article_modified_time":"2016-01-19T13:42:59+00:00","author":"Michel Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Michel Silva"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/","url":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/","name":"Pra\u00e7a da Conjunto Habitacional do PAC - Mapa Cultural da Rocinha","isPartOf":{"@id":"https:\/\/www.falaroca.com\/mapa\/#website"},"datePublished":"2016-01-14T17:46:35+00:00","dateModified":"2016-01-19T13:42:59+00:00","author":{"@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb"},"breadcrumb":{"@id":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.falaroca.com\/mapa\/praca-dos-predios-do-pac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.falaroca.com\/mapa\/"},{"@type":"ListItem","position":2,"name":"Pra\u00e7a da Conjunto Habitacional do PAC"}]},{"@type":"WebSite","@id":"https:\/\/www.falaroca.com\/mapa\/#website","url":"https:\/\/www.falaroca.com\/mapa\/","name":"Mapa Cultural da Rocinha","description":"Mapa Cultural da Rocinha","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.falaroca.com\/mapa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/38885d62bf0950b4eb07a75fe9969ddb","name":"Michel Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.falaroca.com\/mapa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88f5b3e34f8a857ab341971182f8d389?s=96&d=mm&r=g","caption":"Michel Silva"},"url":"https:\/\/www.falaroca.com\/mapa\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/comments?post=452"}],"version-history":[{"count":4,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/452\/revisions"}],"predecessor-version":[{"id":691,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/posts\/452\/revisions\/691"}],"wp:attachment":[{"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/media?parent=452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/categories?post=452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.falaroca.com\/mapa\/wp-json\/wp\/v2\/tags?post=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}